{"id":2722,"date":"2018-12-20T11:16:39","date_gmt":"2018-12-20T10:16:39","guid":{"rendered":"https:\/\/cmesrl.com\/motori-elettrici-autofrenanti\/"},"modified":"2025-06-23T19:06:08","modified_gmt":"2025-06-23T17:06:08","slug":"selbstbremsende-motoren","status":"publish","type":"page","link":"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/","title":{"rendered":"Selbstbremsende Motoren"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2722\" class=\"elementor elementor-2722 elementor-88\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-baa6a5a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"baa6a5a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b38dc24\" data-id=\"b38dc24\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbb1e4b elementor-widget elementor-widget-heading\" data-id=\"dbb1e4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Selbstbremsende Motoren<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77d06f1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"77d06f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c50b63 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c50b63\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-84ed35d\" data-id=\"84ed35d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb2a5e6 elementor-widget elementor-widget-image\" data-id=\"fb2a5e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"746\" src=\"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motoreautofreanante-cme-big.jpg\" class=\"attachment-large size-large wp-image-1190\" alt=\"\" srcset=\"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motoreautofreanante-cme-big.jpg 800w, https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motoreautofreanante-cme-big-300x280.jpg 300w, https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motoreautofreanante-cme-big-768x716.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-41f5f80\" data-id=\"41f5f80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5eb3286 elementor-widget elementor-widget-heading\" data-id=\"5eb3286\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Merkmale:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36f479e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"36f479e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23c0403 elementor-widget elementor-widget-text-editor\" data-id=\"23c0403\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Neben den Standardserien stellt C.M.E. S.r.l. auch selbstbremsende, ein- oder zweipolige Motoren, mit einer oder drei Phasen her. Der Motork\u00f6rper ist identisch mit dem der normalen Motoren, allerdings mit einem l\u00e4ngeren L\u00fcftergeh\u00e4use, das nicht nur den L\u00fcfter enth\u00e4lt, sondern auch das Bremsaggregat sch\u00fctzt.\u00a0<br \/>Die Bremse tritt bei einem Ausfall der Versorgungsspannung in Aktion.\u00a0<br \/>Bei laufendem Motor werden die Federn durch einen Elektromagneten zusammengedr\u00fcckt, der durch die Netzspannung erregt wird. Sobald diese ausf\u00e4llt, entspannen sich die Federn und \u00fcbertragen ihre (als Wert messbare) Kraft auf eine Platte aus Gusseisen oder Stahl, die wiederum auf eine Reibscheibe dr\u00fcckt.\u00a0<br \/><br \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eae7409 elementor-widget elementor-widget-button\" data-id=\"eae7409\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/cmesrl.com\/de\/kontakte\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<i class=\"fa fa-long-arrow-right\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">kontaktieren Sie uns<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-96106a8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"96106a8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8484761\" data-id=\"8484761\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-085f33c elementor-widget elementor-widget-text-editor\" data-id=\"085f33c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Welchen selbstbremsenden Motor w\u00e4hlen?<\/h4><p>Die Erregung des Elektromagneten kann mit Wechselstrom oder Gleichstrom erfolgen. Normalerweise befinden sich die elektrischen Anschl\u00fcsse der Bremse am Klemmenbrett des Motors, auf Anfrage kann aber auch ein eigenes Klemmenbrett f\u00fcr eine separate Stromversorgung vorgesehen werden.\u00a0<br \/>Bei der Auswahl des selbstbremsenden Motors sind folgende Parameter f\u00fcr die Festlegung der entsprechenden Gr\u00f6\u00dfe von Bremse und Motor zu ber\u00fccksichtigen:\u00a0<\/p><ul class=\"normal\"><li>die gew\u00fcnschte Bremsverz\u00f6gerung<\/li><li>die Anzahl von Anl\u00e4ufen\/Stundea<\/li><li>die auf die Welle einwirkende (und zu bremsende) Schwungmasse.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b8c7fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b8c7fa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-38fc52b\" data-id=\"38fc52b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a19be43 elementor-widget elementor-widget-text-editor\" data-id=\"a19be43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Cme srl stellt drei Bremsentypen:<\/h2><h2>\u00a0<\/h2><ul class=\"normal\"><li><i class=\"fa fa-arrow-right\"><\/i>\u00a0BREMSART \u201eK\u201c (Gleichstrombremse)<\/li><li><i class=\"fa fa-arrow-right\"><\/i>\u00a0BREMSART \u201eAC\u201c (Wechselstrombremse)<\/li><li><i class=\"fa fa-arrow-right\"><\/i>\u00a0BREMSART \u201eS\u201c (Retarder)<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-479413e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"479413e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-030e839\" data-id=\"030e839\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c570ab3 elementor-widget elementor-widget-heading\" data-id=\"c570ab3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A.\tBREMSART \u201eK\u201c (Gleichstrombremse)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b8df79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b8df79\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aac2a71\" data-id=\"aac2a71\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-908d5ca elementor-widget elementor-widget-text-editor\" data-id=\"908d5ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Diese Variante wird normalerweise f\u00fcr einen weniger abrupten und mehr stufenweisen Anlauf gew\u00e4hlt. Das wirkt sich jedoch nicht auf das Bremsmoment aus, das in jedem Fall dem einer Wechselstrombremse gleicht..<br \/><br \/>Merkmale:\u00a0<br \/><br \/><\/p><ul class=\"normal\"><li>\u00a0<\/li><li><i class=\"fa fa-angle-right\"><\/i>\u00a0\u00c4u\u00dferst robuste Struktur.<\/li><li><i class=\"fa fa-angle-right\"><\/i>\u00a0Ger\u00e4uscharme Eingriffe und Betrieb<\/li><li><i class=\"fa fa-angle-right\"><\/i>\u00a0Gute Bremsprogression<\/li><li><i class=\"fa fa-angle-right\"><\/i>\u00a0Gute W\u00e4rmeableitung aufgrund der Bel\u00fcftung und der Leitf\u00e4higkeit der Motorabdeckung, die in jedem Fall aus Gusseisen oder Stahl bestehen muss, da sie auch als Bremsoberfl\u00e4che fungiert<\/li><li><i class=\"fa fa-angle-right\"><\/i>\u00a0Die Erregerspule ist komplett in Epoxidharz gekapselt, die mechanischen Teile sind mit einem galvanischen Feuchtigkeitsschutz versehen<\/li><li><i class=\"fa fa-angle-right\"><\/i>\u00a0Auf Anfrage ist eine Ausf\u00fchrung mit manuellem Freigabehebel erh\u00e4ltlich..<\/li><\/ul><p><br \/>Wenn allerdings eine schnelle Bremsung gew\u00fcnscht wird, kann ein spezieller Gleichrichter (Typ R) eingebaut werden, der f\u00fcr eine sofortige Anziehung des Ankers an der Bremse sorgt. Der Gleichrichter ist mit einem statischen Schalter ausgestattet, der den Gleichstromkreis \u00f6ffnet, sobald die Wechselstromspannung wegf\u00e4llt, und damit den Anker umgehend freigibt.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c13782f elementor-widget elementor-widget-image\" data-id=\"c13782f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"724\" src=\"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motore-esploso-2018-Kok-1024x724.png\" class=\"attachment-large size-large wp-image-1194\" alt=\"\" srcset=\"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motore-esploso-2018-Kok-1024x724.png 1024w, https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motore-esploso-2018-Kok-300x212.png 300w, https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motore-esploso-2018-Kok-768x543.png 768w, https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motore-esploso-2018-Kok.png 1181w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68f8555 elementor-widget elementor-widget-text-editor\" data-id=\"68f8555\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"span12\"><p>K &#8211; GLEICHSTROMBREMSE\u00a0<br \/><br \/><\/p><ul><li>1 &#8211; Wellengeh\u00e4use<\/li><li>2 &#8211; Keil<\/li><li>3 &#8211; Lagerschild<\/li><li>4 &#8211; Kompensationsring<\/li><li>5 &#8211; Lager<\/li><li>6 &#8211; Motorwelle<\/li><li>7 &#8211; L\u00e4ufer<\/li><li>8 &#8211; Gewickelter Stator<\/li><li>9 &#8211; Geh\u00e4use<\/li><li>10 &#8211; \u00d6ffnung zur Kabeleinf\u00fchrung<\/li><li>11 &#8211; Klemmbrett f\u00fcr Netzanschluss<\/li><li>12 &#8211; Dichtung IP55<\/li><li>13 &#8211; Klemmenkasten &#8211; Unterbau<\/li><li>14 &#8211; Dichtung IP65<\/li><li>15 &#8211; Klemmenkasten-Deckel<\/li><li>16 &#8211; Lagerschild Bremse K-AC<\/li><li>17 &#8211; Antriebsnabe Bremsscheibe<\/li><li>18 &#8211; Spannring<\/li><li>19 &#8211; Bremsscheibe<\/li><li>20 &#8211; Magnetisches Bremsaggregat \u201eK\u201c<\/li><li>21 &#8211; Manueller Freigabehebel (optional)<\/li><li>22 &#8211; K\u00fchlluftgebl\u00e4se aus PVC<\/li><li>23 &#8211; Feststellring L\u00fcfter<\/li><li>24 &#8211; Verl\u00e4ngertes L\u00fcftergeh\u00e4use<\/li><li>25 &#8211; Motorschild<\/li><\/ul><p>Die Stromversorgung erfolgt durch einen Gleichrichter, der den Strom aus den Klemmen des Klemmenbrettes entnimmt, bei einer Standardspannung von 230 Vol t\u00b1 10 % und Hz 50.\u00a0<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52e91bc elementor-widget elementor-widget-image\" data-id=\"52e91bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"945\" height=\"757\" src=\"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2019\/02\/autofrK16d.png\" class=\"attachment-large size-large wp-image-3468\" alt=\"BREMSART \u201eK\u201c (Gleichstrombremse)\" srcset=\"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2019\/02\/autofrK16d.png 945w, https:\/\/www.cmesrl.com\/wp-content\/uploads\/2019\/02\/autofrK16d-300x240.png 300w, https:\/\/www.cmesrl.com\/wp-content\/uploads\/2019\/02\/autofrK16d-768x615.png 768w\" sizes=\"(max-width: 945px) 100vw, 945px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b3a1d2 elementor-widget elementor-widget-text-editor\" data-id=\"6b3a1d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><a href=\"https:\/\/cmesrl.com\/wp-content\/uploads\/2019\/02\/MOTEURS-de.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-619\" src=\"https:\/\/cmesrl.com\/wp-content\/uploads\/2019\/01\/pdfdownaload.png\" alt=\"pdfdownaload\" width=\"99\" height=\"126\" \/><\/a><\/h2><p><a href=\"https:\/\/cmesrl.com\/wp-content\/uploads\/2019\/02\/MOTEURS-de.pdf\"><strong>Gebrauchsanleitung (pdf)<\/strong><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f8b5b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f8b5b3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9c53f17\" data-id=\"9c53f17\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28104d1 elementor-widget elementor-widget-heading\" data-id=\"28104d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">B. BREMSART \u201eAC\u201c (Wechselstrombremse)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b33c99e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b33c99e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4bfb480\" data-id=\"4bfb480\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6903ab8 elementor-widget elementor-widget-text-editor\" data-id=\"6903ab8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Diese Bremsart wird vorgezogen, wenn ein Motor h\u00e4ufige Spiele mit schneller und kr\u00e4ftiger Bremsung durchf\u00fchren muss. Au\u00dferdem erh\u00e4lt man dadurch st\u00e4ndig variable Bremsmomente, die 200% des Nennbremsmoments des Motors erreichen und deutlich \u00fcberschreiten. Eine umgehende Anziehung des Ankers erm\u00f6glicht, dass der Motor nie mit gebremster Welle startet.<br \/><br \/><br \/>Merkmale:<br \/><br \/><\/p><ul class=\"normal\"><li><i class=\"fa fa-angle-right\"><\/i>\u00a0\u00c4u\u00dferst robuste Struktur<\/li><li><i class=\"fa fa-angle-right\"><\/i>\u00a0Ger\u00e4uscharm bei der Bet\u00e4tigung<\/li><li><i class=\"fa fa-angle-right\"><\/i>\u00a0Gute Bremsprogression<\/li><li><i class=\"fa fa-angle-right\"><\/i>\u00a0Gute W\u00e4rmeableitung aufgrund der Leitf\u00e4higkeit des Bremsk\u00f6rpers aus druckgegossenem Aluminium und der Motorbel\u00fcftung<\/li><li><i class=\"fa fa-angle-right\"><\/i>\u00a0Die Erregerspule ist komplett in Epoxidharz gekapselt.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae6ab72 elementor-widget elementor-widget-image\" data-id=\"ae6ab72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" src=\"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motore-esploso-2018-AC-1024x724.png\" class=\"attachment-large size-large wp-image-1206\" alt=\"\" srcset=\"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motore-esploso-2018-AC-1024x724.png 1024w, https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motore-esploso-2018-AC-300x212.png 300w, https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motore-esploso-2018-AC-768x543.png 768w, https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motore-esploso-2018-AC.png 1181w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f6af90 elementor-widget elementor-widget-text-editor\" data-id=\"8f6af90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"span12\"><p>LEGENDE: AC &#8211; WECHSELSTROMBREMSE\u00a0<br \/><br \/><\/p><ul class=\"normal\"><li>1 &#8211; Wellengeh\u00e4use<\/li><li>2 &#8211; Keil<\/li><li>3 &#8211; Lagerschild<\/li><li>4 &#8211; Kompensationsring<\/li><li>5 &#8211; Lager<\/li><li>6 &#8211; Motorwelle<\/li><li>7 &#8211; L\u00e4ufer<\/li><li>8 &#8211; Gewickelter Stator<\/li><li>9 &#8211; Geh\u00e4use<\/li><li>10 &#8211; \u00d6ffnung zur Kabeleinf\u00fchrung<\/li><li>11 &#8211; Klemmbrett f\u00fcr Netzanschluss<\/li><li>12 &#8211; Dichtung IP55<\/li><li>13 &#8211; Klemmenkasten &#8211; Unterbau<\/li><li>14 &#8211; Dichtung IP65<\/li><li>15 &#8211; Klemmenkasten-Deckel<\/li><li>16 &#8211; Lagerschild Bremse K-AC<\/li><li>17 &#8211; Antriebsnabe Bremsscheibe<\/li><li>18 &#8211; Spannring<\/li><li>19 &#8211; Bremsscheibe<\/li><li>20 &#8211; Magnetisches Bremsaggregat \u201cAC\u201d<\/li><li>21 &#8211; Manueller Freigabehebel (optional)<\/li><li>22 &#8211; K\u00fchlluftgebl\u00e4se aus PVC<\/li><li>23 &#8211; Feststellring L\u00fcfter<\/li><li>24 &#8211; Verl\u00e4ngertes L\u00fcftergeh\u00e4use<\/li><li>25 &#8211; Motorschild<\/li><\/ul><p>Die Versorgungsspannung der normalen Serienmotoren liegt bei 230 \/ 400 Volt 50 Hz. Die f\u00fcr die Bremse notwendige Spannung wird aus den Klemmen des Klemmenbrettes entnommen.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e0bab4 elementor-widget elementor-widget-image\" data-id=\"4e0bab4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"945\" height=\"757\" src=\"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2019\/02\/autofrAC16d.png\" class=\"attachment-large size-large wp-image-3473\" alt=\"\" srcset=\"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2019\/02\/autofrAC16d.png 945w, https:\/\/www.cmesrl.com\/wp-content\/uploads\/2019\/02\/autofrAC16d-300x240.png 300w, https:\/\/www.cmesrl.com\/wp-content\/uploads\/2019\/02\/autofrAC16d-768x615.png 768w\" sizes=\"(max-width: 945px) 100vw, 945px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f919a02 elementor-widget elementor-widget-text-editor\" data-id=\"f919a02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><a href=\"https:\/\/cmesrl.com\/wp-content\/uploads\/2019\/02\/MOTEURS-de.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-619\" src=\"https:\/\/cmesrl.com\/wp-content\/uploads\/2019\/01\/pdfdownaload.png\" alt=\"pdfdownaload\" width=\"99\" height=\"126\" \/><\/a><br \/><a href=\"https:\/\/cmesrl.com\/wp-content\/uploads\/2019\/02\/MOTEURS-de.pdf\"><strong>Gebrauchsanleitung (pdf)<\/strong><\/a><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46e6fe3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46e6fe3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4670770\" data-id=\"4670770\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81f9e42 elementor-widget elementor-widget-heading\" data-id=\"81f9e42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">C. RETARDER (ODER FESTSTELLBREMSE) (S)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6fb9e22 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6fb9e22\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1fcac18\" data-id=\"1fcac18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16bec79 elementor-widget elementor-widget-text-editor\" data-id=\"16bec79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Diese L\u00f6sung wird angewandt, wenn eine stufenweise, weiche Bremsung gew\u00fcnscht ist. Der L\u00fcfter ist aus Gusseisen und verf\u00fcgt \u00fcber eine enorme Schwungmasse, was den oben erw\u00e4hnten Effekt zur Folge hat. Die Reibscheibe wird bei fehlender Spannung durch die Federn gedr\u00fcckt und streift die R\u00fcckseite des L\u00fcfters, der somit als Bremsscheibe dient. In diesem Fall wird ein Gleichstrombremse verwendet, und die Stromversorgung beim Drehstrommotor wird durch einen Gleichrichter geliefert, der auf dem Klemmenbrett zwischen einer Leiterphase und dem Sternpunkt angeschlossen wird.<br \/><br \/>Merkmale:<br \/><br \/><\/p><ul class=\"normal\"><li><i class=\"fa fa-angle-right\"><\/i>\u00a0\u00c4u\u00dferst robuste Struktur<\/li><li><i class=\"fa fa-angle-right\"><\/i>\u00a0Ger\u00e4uscharme Eingriffe und Betrieb<\/li><li><i class=\"fa fa-angle-right\"><\/i>\u00a0Gute Bremsprogression<\/li><li><i class=\"fa fa-angle-right\"><\/i>\u00a0Optimale W\u00e4rmeableitung, der L\u00fcfter dient auch als Bremsscheibe, was den Vorteil hat, dass die w\u00e4hrend der Bremsung entstehende W\u00e4rme abgeleitet wird und das Reibmaterial nur minimal abgenutzt wird.<\/li><li><i class=\"fa fa-angle-right\"><\/i>Die Spule des Elektromagneten ist komplett mit Epoxidharz gekapselt, die mechanischen Teile sind durch eine tropenfeste Verzinkung gesch\u00fctzt.<\/li><li><i class=\"fa fa-angle-right\"><\/i>\u00a0Vielseitige Einsatzm\u00f6glichkeiten. Die Bremse kann &#8211; vor allem bei Einphasenmotoren &#8211; f\u00fcr jede Anwendung und in beliebiger Position verwendet werden, da die beweglichen Teile keinerlei Schwingung aufweisen.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-beeebcc elementor-widget elementor-widget-image\" data-id=\"beeebcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" src=\"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motore-esploso-2018-S-1024x724.png\" class=\"attachment-large size-large wp-image-1214\" alt=\"\" srcset=\"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motore-esploso-2018-S-1024x724.png 1024w, https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motore-esploso-2018-S-300x212.png 300w, https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motore-esploso-2018-S-768x543.png 768w, https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motore-esploso-2018-S.png 1181w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24cfaf6 elementor-widget elementor-widget-text-editor\" data-id=\"24cfaf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>LEGENDE S &#8211; RETARDER<br \/><br \/><\/p><ul class=\"normal\"><li>1 &#8211; Wellengeh\u00e4use<\/li><li>2 &#8211; Keil<\/li><li>3 &#8211; Lagerschild<\/li><li>4 &#8211; Kompensationsring<\/li><li>5 &#8211; Lager<\/li><li>6 &#8211; Motorwelle<\/li><li>7 &#8211; L\u00e4ufer<\/li><li>8 &#8211; Gewickelter Stator<\/li><li>9 &#8211; Geh\u00e4use<\/li><li>10 &#8211; \u00d6ffnung zur Kabeleinf\u00fchrung<\/li><li>11 &#8211; Klemmbrett f\u00fcr Netzanschluss<\/li><li>12 &#8211; Dichtung IP55<\/li><li>13 &#8211; Klemmenkasten &#8211; Unterbau<\/li><li>14 &#8211; Dichtung IP65<\/li><li>15 &#8211; Klemmenkasten-Deckel<\/li><li>16 &#8211; Lagerschild Bremse \u201eS\u201c<\/li><li>17 &#8211; Feder<\/li><li>18 &#8211; Magnetisches Bremsaggregat \u201eS\u201c<\/li><li>19 &#8211; L\u00fcfter aus Gusseisen<\/li><li>20 &#8211; Einstellschraube<\/li><li>21 &#8211; Unterlegscheibe<\/li><li>22 &#8211; Selbstsichernde Mutter<\/li><li>23 &#8211; L\u00fcftergeh\u00e4use<\/li><li>24 &#8211; Motorschild<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a898e8 elementor-widget elementor-widget-image\" data-id=\"9a898e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"945\" height=\"757\" src=\"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2019\/02\/autofrS16d.png\" class=\"attachment-large size-large wp-image-3478\" alt=\"RETARDER (ODER FESTSTELLBREMSE) (S)\" srcset=\"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2019\/02\/autofrS16d.png 945w, https:\/\/www.cmesrl.com\/wp-content\/uploads\/2019\/02\/autofrS16d-300x240.png 300w, https:\/\/www.cmesrl.com\/wp-content\/uploads\/2019\/02\/autofrS16d-768x615.png 768w\" sizes=\"(max-width: 945px) 100vw, 945px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bbd5cc elementor-widget elementor-widget-text-editor\" data-id=\"0bbd5cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><a href=\"https:\/\/cmesrl.com\/wp-content\/uploads\/2019\/02\/MOTEURS-de.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-619\" src=\"https:\/\/cmesrl.com\/wp-content\/uploads\/2019\/01\/pdfdownaload.png\" alt=\"pdfdownaload\" width=\"99\" height=\"126\" \/><\/a><\/h2><h2><a href=\"https:\/\/cmesrl.com\/wp-content\/uploads\/2019\/02\/MOTEURS-de.pdf\" target=\"_blanck\">Gebrauchsanleitung (pdf)<\/a><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8ca2958 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ca2958\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dc7572c\" data-id=\"dc7572c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17bfe30 elementor-widget elementor-widget-text-editor\" data-id=\"17bfe30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"h2grigio\">Gebrauchsanleitung :<\/h2><p class=\"h2grigio\"><br \/>Um einen ordnungsgem\u00e4\u00dfen Betrieb zu gew\u00e4hrleisten, m\u00fcssen von Zeit zu Zeit der Luftspalt und die Abnutzung des Bremsbelags \u00fcberpr\u00fcft werden.\u00a0<br \/>Der Einstellwert des Luftspaltes betr\u00e4gt 0,2 mm und darf nicht \u00fcber 0,7 mm liegen.\u00a0<br \/>Die Abnutzung ist sowohl durch die Schwunglast als auch durch die Drehgeschwindigkeit und die Bremsh\u00e4ufigkeit bedingt.\u00a0<br \/>Falls der Luftspalt verringert werden muss, sollte er erneut auf den Wert 0,2 eingestellt werden.\u00a0<br \/>Wenn mehr als 3 mm des Reibmaterials verbraucht sind, muss die Scheibe ausgewechselt werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cc8cafe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cc8cafe\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-701221b5\" data-id=\"701221b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-732e203a elementor-widget elementor-widget-heading\" data-id=\"732e203a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>Sind Sie an diesem Produkt interessiert?<br><\/b>  Kontaktieren Sie uns f\u00fcr weitere Informationen.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f0b7690 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3f0b7690\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/cmesrl.com\/de\/kontakte\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<i class=\"fa fa-long-arrow-right\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Informationen anfordern<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Selbstbremsende Motoren Merkmale: Neben den Standardserien stellt C.M.E. S.r.l. auch selbstbremsende, ein- oder zweipolige Motoren, mit einer oder drei Phasen her. Der Motork\u00f6rper ist identisch mit dem der normalen Motoren, allerdings mit einem l\u00e4ngeren L\u00fcftergeh\u00e4use, das nicht nur den L\u00fcfter enth\u00e4lt, sondern auch das Bremsaggregat sch\u00fctzt.\u00a0Die Bremse tritt bei einem Ausfall der Versorgungsspannung in Aktion.\u00a0Bei [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-2722","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Selbstbremsende Motoren Verkauf und Hersteller Motoren CME<\/title>\n<meta name=\"description\" content=\"Neben der Standardserie produzieren wir auch selbstbremsende Motoren in verschiedenen Polarit\u00e4ten, einfach und doppelt. Info: +39 051 6831072\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Selbstbremsende Motoren Verkauf und Hersteller Motoren CME\" \/>\n<meta property=\"og:description\" content=\"Neben der Standardserie produzieren wir auch selbstbremsende Motoren in verschiedenen Polarit\u00e4ten, einfach und doppelt. Info: +39 051 6831072\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/\" \/>\n<meta property=\"og:site_name\" content=\"Costruzione e Vendita Motori Elettrici CME srl\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CMEmotorielettrici\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-23T17:06:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motoreautofreanante-cme-big.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"746\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/\",\"url\":\"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/\",\"name\":\"Selbstbremsende Motoren Verkauf und Hersteller Motoren CME\",\"isPartOf\":{\"@id\":\"https:\/\/www.cmesrl.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motoreautofreanante-cme-big.jpg\",\"datePublished\":\"2018-12-20T10:16:39+00:00\",\"dateModified\":\"2025-06-23T17:06:08+00:00\",\"description\":\"Neben der Standardserie produzieren wir auch selbstbremsende Motoren in verschiedenen Polarit\u00e4ten, einfach und doppelt. Info: +39 051 6831072\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/#primaryimage\",\"url\":\"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motoreautofreanante-cme-big.jpg\",\"contentUrl\":\"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motoreautofreanante-cme-big.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cmesrl.com\/de\/home-2\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Selbstbremsende Motoren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cmesrl.com\/#website\",\"url\":\"https:\/\/www.cmesrl.com\/\",\"name\":\"Motori Elettrici Produzione Vendita CME\",\"description\":\"Costruzione e Vendita Motori Elettrici CME srl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cmesrl.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Selbstbremsende Motoren Verkauf und Hersteller Motoren CME","description":"Neben der Standardserie produzieren wir auch selbstbremsende Motoren in verschiedenen Polarit\u00e4ten, einfach und doppelt. Info: +39 051 6831072","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/","og_locale":"de_DE","og_type":"article","og_title":"Selbstbremsende Motoren Verkauf und Hersteller Motoren CME","og_description":"Neben der Standardserie produzieren wir auch selbstbremsende Motoren in verschiedenen Polarit\u00e4ten, einfach und doppelt. Info: +39 051 6831072","og_url":"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/","og_site_name":"Costruzione e Vendita Motori Elettrici CME srl","article_publisher":"https:\/\/www.facebook.com\/CMEmotorielettrici\/","article_modified_time":"2025-06-23T17:06:08+00:00","og_image":[{"width":800,"height":746,"url":"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motoreautofreanante-cme-big.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/","url":"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/","name":"Selbstbremsende Motoren Verkauf und Hersteller Motoren CME","isPartOf":{"@id":"https:\/\/www.cmesrl.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/#primaryimage"},"image":{"@id":"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motoreautofreanante-cme-big.jpg","datePublished":"2018-12-20T10:16:39+00:00","dateModified":"2025-06-23T17:06:08+00:00","description":"Neben der Standardserie produzieren wir auch selbstbremsende Motoren in verschiedenen Polarit\u00e4ten, einfach und doppelt. Info: +39 051 6831072","breadcrumb":{"@id":"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/#primaryimage","url":"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motoreautofreanante-cme-big.jpg","contentUrl":"https:\/\/www.cmesrl.com\/wp-content\/uploads\/2018\/12\/motoreautofreanante-cme-big.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cmesrl.com\/de\/selbstbremsende-motoren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cmesrl.com\/de\/home-2\/"},{"@type":"ListItem","position":2,"name":"Selbstbremsende Motoren"}]},{"@type":"WebSite","@id":"https:\/\/www.cmesrl.com\/#website","url":"https:\/\/www.cmesrl.com\/","name":"Motori Elettrici Produzione Vendita CME","description":"Costruzione e Vendita Motori Elettrici CME srl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cmesrl.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.cmesrl.com\/de\/wp-json\/wp\/v2\/pages\/2722"}],"collection":[{"href":"https:\/\/www.cmesrl.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cmesrl.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cmesrl.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cmesrl.com\/de\/wp-json\/wp\/v2\/comments?post=2722"}],"version-history":[{"count":21,"href":"https:\/\/www.cmesrl.com\/de\/wp-json\/wp\/v2\/pages\/2722\/revisions"}],"predecessor-version":[{"id":7681,"href":"https:\/\/www.cmesrl.com\/de\/wp-json\/wp\/v2\/pages\/2722\/revisions\/7681"}],"wp:attachment":[{"href":"https:\/\/www.cmesrl.com\/de\/wp-json\/wp\/v2\/media?parent=2722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}